{"id":3185,"date":"2024-01-21T03:51:44","date_gmt":"2024-01-21T03:51:44","guid":{"rendered":"https:\/\/brentharshlaw.com\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/"},"modified":"2024-01-21T03:51:44","modified_gmt":"2024-01-21T03:51:44","slug":"lesiones-laborales-cuando-contratar-a-un-abogado","status":"publish","type":"post","link":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/","title":{"rendered":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado"},"content":{"rendered":"<p>Una lesi\u00f3n que se produce en el trabajo o en su lugar de trabajo entra en la categor\u00eda de \u00abLesiones por accidentes de trabajo\u00bb.<\/p>\n<p>Es crucial que usted reciba la atenci\u00f3n m\u00e9dica adecuada para recuperarse de su lesi\u00f3n, pero muchos lugares de trabajo tratan de minimizar la gravedad de las lesiones de compensaci\u00f3n de trabajadores, limitar la cantidad de compensaci\u00f3n pagada al trabajador lesionado, o en algunos casos &#8211; incluso tratar de echar la culpa a la persona que se lesion\u00f3.<\/p>\n<h2>\u00bfCu\u00e1ndo debo contratar a un abogado laboralista?<\/h2>\n<p>Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. El abogado revisar\u00e1 con usted los hechos de su lesi\u00f3n y ser\u00e1 su defensor para asegurarse de que recibe la atenci\u00f3n m\u00e9dica adecuada y cualquier indemnizaci\u00f3n necesaria para recuperarse de su lesi\u00f3n.<\/p>\n<p>El proceso de compensaci\u00f3n de los trabajadores es confuso e incluso los mejores empresarios buscan minimizar sus p\u00e9rdidas y conseguir que vuelvas al trabajo lo antes posible. El abogado que usted contrata para que le represente s\u00f3lo lucha por sus intereses, no por los de la empresa.<\/p>\n<h2>\u00bfCu\u00e1les son las lesiones laborales m\u00e1s comunes?<\/h2>\n<p>Las lesiones que se producen en el trabajo o en el lugar de trabajo pueden ser muy variadas. Las lesiones m\u00e1s comunes que dan derecho a una indemnizaci\u00f3n por accidente laboral son: cortes profundos o desgarros en la piel (laceraciones), esguinces y distensiones (rotura de ligamentos, m\u00fasculos o tendones), contusiones o hematomas, quemaduras, lesiones oculares y faciales, fracturas \u00f3seas y traumatismos acumulativos (t\u00e9rmino que designa las lesiones derivadas de tareas repetitivas durante periodos de tiempo prolongados).<\/p>\n<h2>\u00bfC\u00f3mo se calcula la indemnizaci\u00f3n por accidente laboral?<\/h2>\n<p>La indemnizaci\u00f3n por accidente laboral tiene en cuenta diversos factores. Estos factores suelen incluir el alcance de la lesi\u00f3n, el coste de la atenci\u00f3n m\u00e9dica para tratar y rehabilitar una lesi\u00f3n, los salarios perdidos por el tiempo de baja laboral para recuperarse de una lesi\u00f3n y las prestaciones a las familias de los empleados fallecidos en accidentes laborales.<\/p>\n<p>Es importante revisar los hechos de su caso de compensaci\u00f3n de trabajadores con un abogado local de compensaci\u00f3n de trabajadores, ya que pueden darle una idea de qu\u00e9 tipo de compensaci\u00f3n tiene derecho a recibir.<\/p>\n<h2>\u00bfQu\u00e9 lesiones no cubre la indemnizaci\u00f3n por accidente laboral?<\/h2>\n<p>La mayor\u00eda de las lesiones en el trabajo o en el lugar de trabajo est\u00e1n cubiertas por la indemnizaci\u00f3n por accidente laboral, pero hay varias excepciones. La lesi\u00f3n debe ocurrir durante el \u00abcurso y alcance de su empleo\u00bb. B\u00e1sicamente, si realizaba una actividad que beneficia a su empresa o es una de sus obligaciones laborales, su lesi\u00f3n estar\u00e1 cubierta.<\/p>\n<p>Lo que no est\u00e1 cubierto var\u00eda seg\u00fan la ley estatal, pero lo siguiente no suele estar cubierto por la compensaci\u00f3n de los trabajadores: una lesi\u00f3n intencionada, cualquier actividad ilegal, los desplazamientos al trabajo y a casa desde el trabajo, un evento recreativo o social voluntario, si est\u00e1s intoxicado cuando se produce la lesi\u00f3n, o si participas en payasadas o peleas. Aunque no suelen estar cubiertos por la indemnizaci\u00f3n por accidente de trabajo, es importante que hables con un abogado sobre tu caso particular de indemnizaci\u00f3n por accidente de trabajo. Puede haber ciertos hechos acerca de su situaci\u00f3n en la que su lesi\u00f3n caer\u00e1 bajo el paraguas de compensaci\u00f3n del trabajador.<\/p>\n<h2>\u00bfQu\u00e9 debo decir o no decir a un m\u00e9dico de accidentes de trabajo?<\/h2>\n<p>Si habla con un abogado especializado en indemnizaciones por accidentes de trabajo, le dir\u00e1 que sea siempre sincero sobre su lesi\u00f3n. No mienta ni exagere nunca a un m\u00e9dico o al representante del seguro de accidentes de trabajo. A menudo, su empresa quiere asegurarse de que est\u00e1 sano y bien atendido, sobre todo si sufre una lesi\u00f3n en el trabajo. Mentir o inventarse cualquier cosa sobre su lesi\u00f3n se descubrir\u00e1 a menudo y puede desacreditar toda su demanda por lesiones. Sea sincero con cualquier m\u00e9dico que vea por su lesi\u00f3n y mantenga una comunicaci\u00f3n abierta con su abogado de compensaci\u00f3n de trabajadores.<\/p>\n<h2>\u00bfCu\u00e1les son las causas habituales de los accidentes laborales?<\/h2>\n<p>Las lesiones por accidentes de trabajo pueden deberse a muchas causas, pero las m\u00e1s comunes son: manipulaci\u00f3n de materiales, resbalones y ca\u00eddas, golpes con objetos, accidentes con herramientas y lesiones repetitivas de larga duraci\u00f3n.<\/p>\n<p>Si usted ha sufrido una lesi\u00f3n en su lugar de trabajo o durante el curso de su trabajo, vale la pena su tiempo para hablar con un abogado de compensaci\u00f3n de trabajadores con experiencia. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una lesi\u00f3n que se produce en el trabajo o en su lugar de trabajo entra en la categor\u00eda de \u00abLesiones por accidentes de trabajo\u00bb. Es crucial que usted reciba la atenci\u00f3n m\u00e9dica adecuada para recuperarse de su lesi\u00f3n, pero muchos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-3185","post","type-post","status-publish","format-standard","has-post-thumbnail","category-danos-corporales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law<\/title>\n<meta name=\"description\" content=\"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law\" \/>\n<meta property=\"og:description\" content=\"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/\" \/>\n<meta property=\"og:site_name\" content=\"Brent Harsh Law\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-21T03:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png\" \/>\n<meta name=\"author\" content=\"Brent Harsh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brent Harsh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/\"},\"author\":{\"name\":\"Brent Harsh\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#\\\/schema\\\/person\\\/100120bddb69685e7cbc8815349b7124\"},\"headline\":\"Lesiones laborales: Cu\u00e1ndo contratar a un abogado\",\"datePublished\":\"2024-01-21T03:51:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/\"},\"wordCount\":836,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CHL_1.png\",\"articleSection\":[\"Da\u00f1os corporales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/\",\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/\",\"name\":\"Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CHL_1.png\",\"datePublished\":\"2024-01-21T03:51:44+00:00\",\"description\":\"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CHL_1.png\",\"contentUrl\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CHL_1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/lesiones-laborales-cuando-contratar-a-un-abogado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/inicio-nuevo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lesiones laborales: Cu\u00e1ndo contratar a un abogado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/\",\"name\":\"Brent Harsh Law\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#organization\"},\"alternateName\":\"Personal Injury Attorneys\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#organization\",\"name\":\"Brent Harsh Law\",\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Brent-Harsh-Law-Logo-blue.png\",\"contentUrl\":\"https:\\\/\\\/brentharshlaw.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Brent-Harsh-Law-Logo-blue.png\",\"width\":1636,\"height\":508,\"caption\":\"Brent Harsh Law\"},\"image\":{\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/#\\\/schema\\\/person\\\/100120bddb69685e7cbc8815349b7124\",\"name\":\"Brent Harsh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g\",\"caption\":\"Brent Harsh\"},\"description\":\"The founder and managing partner at the firm, Brent Harsh received his Juris Doctor from the University of Pacific, McGeorge School of Law in 2001. He also graduated from the University of Nevada in 1996 with his Bachelor of Science in Finance, with a minor in Economics. Brent is certified by the Nevada State Bar as a Personal Injury Specialist, as well as the State Bars of Oregon and Washington. He began his career as a Deputy District Attorney, but soon started representing insurance companies. In his 20 years of insurance defense work, a decade of which was spent with Farmers Insurance as a Senior Trial Attorney where he tried cases valued over $10,000,000. Brent has tried over 100 cases. His vast experience, coupled with an aggressive yet approachable style, has both insurance companies and large corporations that have injured his clients settling cases early, and has won cases time and time again. Outside of the courtroom, Brent is an in-demand educator who has been invited to lecture other attorneys due to his expertise in the areas of litigation, civil practice, personal injury, insurance law, and insurance bad-faith litigation. A true Reno local who graduated from Reno High School, Brent spends as much time as possible outdoors, as a triathlete, marathon runner, bicyclist, and motorcyclist. This intimate relationship with the local community combined with his deep understanding of insurance law makes Brent a fantastic ally for his clients.\",\"sameAs\":[\"https:\\\/\\\/brentharshlaw.com\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/brent-harsh-6aa321145\\\/\"],\"url\":\"https:\\\/\\\/brentharshlaw.com\\\/es\\\/blog\\\/author\\\/coulterharsh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law","description":"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/","og_locale":"es_ES","og_type":"article","og_title":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law","og_description":"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.","og_url":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/","og_site_name":"Brent Harsh Law","article_published_time":"2024-01-21T03:51:44+00:00","og_image":[{"url":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png","type":"","width":"","height":""}],"author":"Brent Harsh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brent Harsh","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#article","isPartOf":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/"},"author":{"name":"Brent Harsh","@id":"https:\/\/brentharshlaw.com\/es\/#\/schema\/person\/100120bddb69685e7cbc8815349b7124"},"headline":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado","datePublished":"2024-01-21T03:51:44+00:00","mainEntityOfPage":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/"},"wordCount":836,"commentCount":0,"publisher":{"@id":"https:\/\/brentharshlaw.com\/es\/#organization"},"image":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#primaryimage"},"thumbnailUrl":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png","articleSection":["Da\u00f1os corporales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/","url":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/","name":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado - Brent Harsh Law","isPartOf":{"@id":"https:\/\/brentharshlaw.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#primaryimage"},"image":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#primaryimage"},"thumbnailUrl":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png","datePublished":"2024-01-21T03:51:44+00:00","description":"Si se ha lesionado en el trabajo o en su lugar de trabajo, debe ponerse en contacto con un abogado con experiencia en compensaci\u00f3n de trabajadores. P\u00f3ngase en contacto con nosotros hoy mismo para estudiar su reclamaci\u00f3n.","breadcrumb":{"@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#primaryimage","url":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png","contentUrl":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2022\/02\/CHL_1.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/brentharshlaw.com\/es\/blog\/lesiones-laborales-cuando-contratar-a-un-abogado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/brentharshlaw.com\/es\/inicio-nuevo\/"},{"@type":"ListItem","position":2,"name":"Lesiones laborales: Cu\u00e1ndo contratar a un abogado"}]},{"@type":"WebSite","@id":"https:\/\/brentharshlaw.com\/es\/#website","url":"https:\/\/brentharshlaw.com\/es\/","name":"Brent Harsh Law","description":"","publisher":{"@id":"https:\/\/brentharshlaw.com\/es\/#organization"},"alternateName":"Personal Injury Attorneys","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brentharshlaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/brentharshlaw.com\/es\/#organization","name":"Brent Harsh Law","url":"https:\/\/brentharshlaw.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/brentharshlaw.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2023\/11\/Brent-Harsh-Law-Logo-blue.png","contentUrl":"https:\/\/brentharshlaw.com\/wp-content\/uploads\/2023\/11\/Brent-Harsh-Law-Logo-blue.png","width":1636,"height":508,"caption":"Brent Harsh Law"},"image":{"@id":"https:\/\/brentharshlaw.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/brentharshlaw.com\/es\/#\/schema\/person\/100120bddb69685e7cbc8815349b7124","name":"Brent Harsh","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5769e54ffd2addd20ad6569d4ee23d662891041441366ab872f5551afa6f300?s=96&d=mm&r=g","caption":"Brent Harsh"},"description":"The founder and managing partner at the firm, Brent Harsh received his Juris Doctor from the University of Pacific, McGeorge School of Law in 2001. He also graduated from the University of Nevada in 1996 with his Bachelor of Science in Finance, with a minor in Economics. Brent is certified by the Nevada State Bar as a Personal Injury Specialist, as well as the State Bars of Oregon and Washington. He began his career as a Deputy District Attorney, but soon started representing insurance companies. In his 20 years of insurance defense work, a decade of which was spent with Farmers Insurance as a Senior Trial Attorney where he tried cases valued over $10,000,000. Brent has tried over 100 cases. His vast experience, coupled with an aggressive yet approachable style, has both insurance companies and large corporations that have injured his clients settling cases early, and has won cases time and time again. Outside of the courtroom, Brent is an in-demand educator who has been invited to lecture other attorneys due to his expertise in the areas of litigation, civil practice, personal injury, insurance law, and insurance bad-faith litigation. A true Reno local who graduated from Reno High School, Brent spends as much time as possible outdoors, as a triathlete, marathon runner, bicyclist, and motorcyclist. This intimate relationship with the local community combined with his deep understanding of insurance law makes Brent a fantastic ally for his clients.","sameAs":["https:\/\/brentharshlaw.com\/","https:\/\/www.linkedin.com\/in\/brent-harsh-6aa321145\/"],"url":"https:\/\/brentharshlaw.com\/es\/blog\/author\/coulterharsh\/"}]}},"_links":{"self":[{"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/posts\/3185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/comments?post=3185"}],"version-history":[{"count":0,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/posts\/3185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/media\/1839"}],"wp:attachment":[{"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/media?parent=3185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/categories?post=3185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brentharshlaw.com\/es\/wp-json\/wp\/v2\/tags?post=3185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}